{"id":32666,"date":"2018-10-23T23:53:54","date_gmt":"2018-10-23T21:53:54","guid":{"rendered":"https:\/\/www.datalex.ch\/terms-of-use\/"},"modified":"2025-04-29T11:10:59","modified_gmt":"2025-04-29T09:10:59","slug":"terms-of-use","status":"publish","type":"page","link":"https:\/\/www.datalex.ch\/en\/terms-of-use\/","title":{"rendered":"Terms of use"},"content":{"rendered":"<div id='av-layout-grid-1'  class='av-layout-grid-container av-1xv46md-6eb156b8eebd81d165fc620cd817a6a6 entry-content-wrapper main_color av-flex-cells  avia-builder-el-0  el_before_av_one_full  avia-builder-el-first   container_wrap sidebar_right'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jlmf21a8-74fd8e01cf8364d6ab56a90b5c0dcf12\">\n.flex_cell.av-jlmf21a8-74fd8e01cf8364d6ab56a90b5c0dcf12{\nvertical-align:top;\npadding:30px 30px 30px 30px;\nbackground:url(https:\/\/www.datalex.ch\/cms\/wp-content\/uploads\/2019\/10\/datalex_photo-1519120126473-8be7aedcd6c6-845x684.jpeg) 0% 0% no-repeat scroll ;\n}\n<\/style>\n<div class='flex_cell av_one_third av-jlmf21a8-74fd8e01cf8364d6ab56a90b5c0dcf12 no_margin  avia-builder-el-1  el_before_av_cell_two_third  avia-builder-el-first  avia-full-stretch' ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jlmfgryc-cdc2500320bf76144cace57cdddcff77\">\n.flex_column.av-jlmfgryc-cdc2500320bf76144cace57cdddcff77{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\npadding:30px 30px 30px 30px;\nbackground-color:rgba(0,0,0,0.09);\n}\n<\/style>\n<div class='flex_column av-jlmfgryc-cdc2500320bf76144cace57cdddcff77 av_one_full  avia-builder-el-2  avia-builder-el-no-sibling  first flex_column_div '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_heading-63449d93ff282b29db3a8cad6ca85f4b\">\n#top .av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b{\nmargin:25px 0 0 0;\npadding-bottom:10px;\ncolor:#ffffff;\nfont-size:35px;\n}\nbody .av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .av-special-heading-tag{\nfont-size:35px;\n}\n.av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 768px) and (max-width: 989px){ \n#top #wrap_all .av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .av-special-heading-tag{\nfont-size:24px;\n}\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-av_heading-63449d93ff282b29db3a8cad6ca85f4b .av-special-heading-tag{\nfont-size:30px;\n}\n}\n<\/style>\n<div  class='av-special-heading av-av_heading-63449d93ff282b29db3a8cad6ca85f4b av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-3  avia-builder-el-no-sibling  av-inherit-size av-linked-heading'><h1 class='av-special-heading-tag'  itemprop=\"headline\"  >TERMS OF USE<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-zfs9s5-1876319c668c8da4c17622a779a1e345\">\n.flex_cell.av-zfs9s5-1876319c668c8da4c17622a779a1e345{\nvertical-align:top;\npadding:30px 30px 30px 30px;\n}\n<\/style>\n<div class='flex_cell av_two_third av-zfs9s5-1876319c668c8da4c17622a779a1e345 no_margin  avia-builder-el-4  el_after_av_cell_one_third  avia-builder-el-last ' ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2q7pft1-59a3a82340a2549d118350f7e45e0742\">\n.flex_column.av-2q7pft1-59a3a82340a2549d118350f7e45e0742{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\npadding:10px 10px 10px 10px;\n}\n<\/style>\n<div class='flex_column av-2q7pft1-59a3a82340a2549d118350f7e45e0742 av_one_full  avia-builder-el-5  avia-builder-el-no-sibling  first flex_column_div '   ><section  class='av_textblock_section av-1havy5-9477afd82c4f92046d76158942a5de36'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><h3>BEFORE GETTING STARTED<\/h3>\n<p>datalex is a legal platform designed by Swiss attorneys.<\/p>\n<p>This page describes the terms of use (the &#8220;<strong>Terms<\/strong>&#8220;) by which visitors, members and clients of datalex shall be bound while using this platform.<\/p>\n<p>The terms &#8220;<strong>Platform<\/strong>&#8220;, &#8220;<strong>datalex<\/strong>&#8220;, &#8220;<strong>Service<\/strong>&#8220;, &#8220;<strong>we<\/strong>&#8221; or &#8220;<strong>us<\/strong>&#8221; shall refer to\u00a0this website or datalex llc. Please also refer to our\u00a0<a href=\"https:\/\/www.datalex.ch\/en\/privacy-notice\/\" target=\"_blank\" rel=\"noopener noreferrer\">privacy notice<\/a> to understand how we process information about you.\u00a0 If you do not want us to do so or if you do not agree with the terms as set out in this site, you should not use this platform.<\/p>\n<p>Effective data : <strong>20 January 2019.<\/strong> Last update:\u00a0<strong>20 January 2019<\/strong>.<\/p>\n<\/div><\/section><\/div>\n<\/div><\/div>\n<\/div><div id='after_grid_row_1'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-32666'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2j9rqje-5f34ccc5d94423795464075154b5c09a\">\n.flex_column.av-2j9rqje-5f34ccc5d94423795464075154b5c09a{\nborder-radius:0px 0px 0px 0px;\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-2j9rqje-5f34ccc5d94423795464075154b5c09a av_one_full  avia-builder-el-7  el_after_av_layout_row  avia-builder-el-no-sibling  first flex_column_div av-zero-column-padding '   ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jnm81lbw-9a07dd47b6585787605495c0c6d66a2a\">\n#top .togglecontainer.av-jnm81lbw-9a07dd47b6585787605495c0c6d66a2a p.toggler{\nbackground-color:#f8f8f8;\nborder-color:#0c859a;\n}\n#top .togglecontainer.av-jnm81lbw-9a07dd47b6585787605495c0c6d66a2a .toggle_wrap .toggle_content{\nbackground-color:#f8f8f8;\nborder-color:#0c859a;\n}\n<\/style>\n<div  class='togglecontainer av-jnm81lbw-9a07dd47b6585787605495c0c6d66a2a av-minimal-toggle  avia-builder-el-8  avia-builder-el-no-sibling  toggle_close_all' >\n<section class='av_toggle_section av-79szwa-5339f099ac973774b54c34fc48e42e72'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-1' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1'>1. WHO WE ARE AND WHAT WE OFFER<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p><strong>datalex<\/strong> is an online\u00a0legal platform designed by two Swiss attorneys who are passionate about new technologies and legal Technologies. Our aim is to disrupt the traditional ways legal services are offered with an innovative platform and using our tools, network and technology to ensure our lawyers counsel you in the best, easiest and most flexible way possible. <strong>But not only!<\/strong> We act as an e-Commerce platform to make legal services available to companies. We offer training, legal advice, downloadable documents and develop legal tools for companies, in particular with regard to data protection, privacy, new technologies, digital health, cybercrime contract review in business and commercial law. <strong>Our mission<\/strong>: be flexible while remaining business oriented. We ensure that you can reduce your contractual, legal and business risks, increase your competitiveness and attractiveness on the market. datalex assist you in complying with regulatory aspects (such as data protection in Switzerland and Europe (GDPR), financial markets &#8211; FINMA, as well as in the field of health, medical software and applications, telemedicine, pharmaceutical law, medical devices and health technologies, Swissmedic, cybercrime, commercial deals and negotiation as well as dispute resolution and litigation). This platform is owned and managed by datalex s\u00e0rl, a limited liability company based in Vevey, Switzerland.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-1ru1ly2-8943f2b7f75828fcb9e01de29b001c1d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-2' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2'>2. THIRD PARTY SERVICES<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>By using our services, you agree to the use of third-party services under the terms of these platforms. In particular, datalex is operated via WordPress on which we install several options of tools (plugins) developed by third parties. We ensure that we use such services as far as possible only if they guarantee your privacy and the confidentiality of your data (personal and confidential). If you want to know more about those terms (terms of use, terms and conditions and privacy policy), please refer directly to the specific terms and conditions of each of these main services we use below, such as : <a href=\"https:\/\/www.youtube.com\/t\/terms\">Youtube<\/a> | <a href=\"https:\/\/stripe.com\/ch\/privacy#translation-fr\">Stripe<\/a> You will get more information about how we respect your privacy on our <a href=\"https:\/\/www.datalex.ch\/en\/privacy-notice\/\" target=\"_blank\" rel=\"noopener noreferrer\">privacy notice<\/a>.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-3rrj4q-7d34f0bc619c4cad77ad9cd7e1c6c186'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-3' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3'>3. TARGETTED AUDIENCE FOR THOSE TERMS<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>These conditions apply to any user, visitor, member and client of this Platform, in particular:<\/p>\n<ul>\n<li>to Swiss companies, start-ups, SMEs, public and private institutions, small multinationals;<\/li>\n<li>to all registered members who benefit from our products, services and online tools via this Platform;<\/li>\n<li>to any visitor who would like to know more about data protection, connected health, technologies, innovation and cybercrime.<\/li>\n<\/ul>\n<p>The use of our services implies acceptance of and compliance with the terms contains herein. We reserve the right to change these Terms at any time and, in the event of a major change, will notify you in a timely manner of such changes on this site or in another appropriate manner.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-qa4mm2-a354cc04b7cbf681beb832ee8ffa76a0'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-4' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-4'>4. ACCESS TO DATALEX<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-4' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>You are solely responsible for using the site on your computer and with your technical equipment, Internet access.\u00a0datalex uses all reasonable means to ensure the quality and access to the Service, but has no obligation to do so. datalex cannot be held responsible for any malfunction of the network or servers or any other event beyond its reasonable control that would prevent or degrade access to the site. The same applies to third-party services that may be accessible through our site. We reserve the right to interrupt, temporarily suspend or modify access to all or part of the service without notice, in order to ensure maintenance, or for any other reason, without the interruption giving rise to any obligation or compensation. datalex reserves the right to refuse access to the Service, unilaterally and without prior notice, to any user who does not comply with these general conditions of use.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-av_toggle-a786b1c253561feee58af3311fd6bfde'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-5' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-5'>5. COMMENT UTILISER NOS SERVICES<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-5' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Lorsque vous visitez notre site, vous acc\u00e9derez \u00e0 des informations g\u00e9n\u00e9rales, telles que des nouvelles via notre blog et la \u00ab\u00a0<a href=\"https:\/\/www.datalex.ch\/actualites-rgpd\/\" target=\"_blank\" rel=\"noopener noreferrer\">dataline\u00a0<\/a>\u00bb\u00a0; une cha\u00eene d\u2019informations sur le RGPD et la protection des donn\u00e9es pour votre entreprise, nos newsletters, ainsi que plusieurs services gratuits ou payants via notre boutique en ligne, comme :<\/p>\n<ul>\n<li>des services juridiques en ligne et d\u2019autres prestations de conseils\u00a0;<\/li>\n<li>de la documentation et des packs \u00e0 t\u00e9l\u00e9charger\u00a0;<\/li>\n<li>un portail de r\u00e9servation de rendez-vous en personne ou en ligne\u00a0;<\/li>\n<li>acc\u00e8s \u00e0 des formations et des supports de conf\u00e9rences sur des th\u00e8mes particuliers\u00a0;<\/li>\n<li>des outils juridiques innovants (LegalTech) pour votre entreprise ou pour les individus.<\/li>\n<\/ul>\n<p>Lorsque vous commandez des prestations ou des produits gratuits ou payants, vous devez cr\u00e9er un compte et nous fournir un minimum d\u2019informations pour garantir votre int\u00e9r\u00eat pour ces produits. Cela nous permet \u00e9galement de limiter la fraude au moyen de cartes de cr\u00e9dit.<\/p>\n<p><strong>Utilisation des services en g\u00e9n\u00e9ral<\/strong> Les services de datalex servent aux personnes priv\u00e9es et publiques pour entrer en contact avec nos avocats partenaires, acheter des produits ou commander des prestations offertes par datalex ou nos avocats partenaires. Vous vous engagez \u00e0 utiliser nos services en conformit\u00e9 aux lois en vigueur et \u00e0 nous soumettre toute information qui nous permettrait de pr\u00e9venir les conflits d\u2019int\u00e9r\u00eat. Votre utilisation des services de datalex est aussi soumise \u00e0 tout autre contrat que vous pourriez avoir avec nous, comme les conditions g\u00e9n\u00e9rales de vente. Lorsque vous devenez membre de datalex ou vous inscrivant et cr\u00e9ant un compte, gratuitement ou gr\u00e2ce \u00e0 un abonnement, ces conditions d\u2019utilisation s\u2019appliquent \u00e0 vous. En cas de conflit entre les pr\u00e9sentes conditions et un autre contrat que vous pourriez avoir avec nous, les termes de votre contrat pr\u00e9vaudront.<\/p>\n<p><strong>Interdiction d\u2019offrir nos services \u00e0 des tiers<\/strong> Sauf accord pr\u00e9alable \u00e9crit de notre part, en aucun cas vous ne pouvez utiliser les services de notre plate-forme \u00e0 d\u2019autres fins que celles pr\u00e9vues par notre plate-forme. En particulier, vous devez respecter la licence d\u2019utilisation personnelle qui vous est conf\u00e9r\u00e9e pour utiliser le service. En cas d\u2019utilisation par d\u2019autres personnes qui ne sont pas autoris\u00e9es ou d\u00e9clar\u00e9e ou moment d\u2019une commande nous pouvons vous r\u00e9clamer de payer une licence suppl\u00e9mentaire. Il est interdit de r\u00e9utiliser nos services \u00e0 des fins commerciales ou pour votre propre compte ou le compte d\u2019autrui, en vue de les revendre, louer, compenser avec d\u2019autres cr\u00e9ances, le mettre en usufruit, les d\u00e9compiler. Nos services et le contenu de notre site est prot\u00e9g\u00e9 par le droit d\u2019auteur et de tels actes pourraient \u00eatre consid\u00e9r\u00e9s comme de la concurrence d\u00e9loyale. Vous ne pouvez pas non plus les utiliser afin de nuire \u00e0 des tiers.<\/p>\n<p><strong>Utilisation par les membres inscrits sur datalex<\/strong> Vous vous engagez \u00e0 ne nous transmettre que des informations conformes \u00e0 la r\u00e9alit\u00e9, en particulier en cas de r\u00e9solution conflit ou de litige avec une partie adverser. De plus, vous vous engagez \u00e0 user de toute la prudence n\u00e9cessaire pour limiter au maximum de transmettre des informations personnelles sensibles ou \u00e0 risques. Vous vous engagez \u00e0 ne pas cr\u00e9er de profils pour le compte de tiers, de faux profils, ni mettre en ligne des liens vers des sites tiers ou tout contenu qui serait illicite, inappropri\u00e9 ou contraire aux m\u0153urs. Vous ne pouvez pas utiliser nos services \u00e0 des fins commerciales (vente, revente, location, cession, etc. de nos services \u00e0 des tiers) sans notre accord pr\u00e9alable \u00e9crit.<\/p>\n<p><strong>Par des personnes mineures<\/strong> Toute personne mineure se doit d\u2019\u00eatre mieux prot\u00e9g\u00e9e lors de l\u2019utilisation de services en ligne, mais \u00e9galement pour pr\u00e9venir toute utilisation frauduleuse ou abusive qui serait faite des donn\u00e9es publi\u00e9es d\u2019une personne mineure. Si vous \u00eates mineur, vous devez obtenir l\u2019autorisation de votre repr\u00e9sentant l\u00e9gal pour passer un contrat avec notre plate-forme. Comme il nous est difficile de v\u00e9rifier votre \u00e2ge en ligne, nous pouvons \u00eatre amen\u00e9s \u00e0 vous demander ou \u00e0 votre repr\u00e9sentant l\u00e9gal une pi\u00e8ce d\u2019identit\u00e9 ou de faire valider l\u2019ouverture de votre compte par \u00e9crit ou par oral en vue d\u2019obtenir son consentement.<\/p>\n<p><strong>Votre compte sur datalex<\/strong> Vous pouvez demander la suppression de votre compte \u00e0 tout moment depuis notre portail en ligne ou \u00e0 l\u2019adresse suivante\u00a0: <a href=\"mailto:privacy@datalex.ch\">privacy@datalex.ch<\/a>. Nous effacerons toutes les donn\u00e9es personnelles sauf celles que nous devons conserver pour des raisons l\u00e9gales.<\/p>\n<p>Veuillez lire notre <a href=\"https:\/\/www.datalex.ch\/en\/privacy-notice\/\" target=\"_blank\" rel=\"noopener noreferrer\">politique de confidentialit\u00e9<\/a> pour plus d\u2019informations.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-412ej2v-4030c83e452ff940be72dea1288a8a10'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-6' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-6'>6. LIMITATION DE RESPONSABILITE<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-6' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>datalex exclut toute responsabilit\u00e9 pour faute l\u00e9g\u00e8re. La responsabilit\u00e9 de datalex est exclue pour les violations de contrat dues \u00e0 une n\u00e9gligence l\u00e9g\u00e8re. Ceci s\u2019applique \u00e9galement aux violations de contrats qui sont le fait d\u2019auxiliaires et de substituts. La responsabilit\u00e9 de datalex n\u2019est pas engag\u00e9e pour les erreurs qui ne lui sont pas imputables, qui interviennent notamment au niveau des op\u00e9rateurs de t\u00e9l\u00e9communication, du serveur ou de tout autre tiers prestataire tels que les r\u00e9seaux sociaux et plate-forme de diffusion de contenu en ligne. Pour des raisons de maintenance de la plate-forme, le site peut occasionnellement et temporairement \u00eatre indisponible. Toute op\u00e9ration de maintenance du site s\u2019effectuera, dans la mesure du possible, en dehors des heures de bureau et de pr\u00e9f\u00e9rence durant le week-end. Le Site \u00e9tant accessible depuis le monde entier, la maintenance sera effectu\u00e9e en dehors des heures de bureau en Suisse. Vous \u00eates tenu par les conditions d\u2019utilisation du site et \u00eates responsable du contenu que vous soumettez sur datalex. En aucun cas, nous ne pouvons \u00eatre tenus pour responsables de manquement ou de violation de droits de propri\u00e9t\u00e9 intellectuelle ou de dommage caus\u00e9s \u00e0 des tiers. Vous nous indemniserez de tout montant r\u00e9clam\u00e9 par un tiers en raison d\u2019un comportement qui vous est imputable, qu\u2019il s\u2019agisse d\u2019un dommage direct ou indirect. Notre r\u00e9f\u00e9rencement sur les moteurs de recherche (Google, Yahoo, Bing) et sur les r\u00e9seaux sociaux \u00e9tant r\u00e9alis\u00e9 de mani\u00e8re automatique, datalex ne peut garantir ni exercer de contr\u00f4le de r\u00e9f\u00e9rencement sur ces moteurs de recherche et n&#8217;encourt, d\u00e8s lors aucune responsabilit\u00e9 de positionnement et de visibilit\u00e9. datalex n&#8217;est aucunement responsable des contenus des sites ou des sources externes faisant r\u00e9f\u00e9rence \u00e0 datalex.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-3kiqcc7-18ec931be45ad1a7c578ba7e0c2e721e'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-7' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-7'>7. SIGNALEMENT EN CAS DE CONTENU ILLICITE<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-7' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Si vous pensez que du contenu enfreint vos droits ou les droits de tiers, nous vous prions de nous en informer imm\u00e9diatement afin que nous puissions examiner votre demande et, cas \u00e9ch\u00e9ant, prendre les mesures ad\u00e9quates pour mettre fin \u00e0 toute violation. Tout signalement doit nous parvenir \u00e0 l\u2019adresse suivante\u00a0: <a href=\"http:\/\/support@datalex.ch\" target=\"_blank\" rel=\"noopener noreferrer\">support@datalex<\/a> et dans les meilleurs d\u00e9lais. Par ces conditions d\u2019utilisation, vous renoncez \u00e0 toute pr\u00e9tention \u00e0 notre encontre pour tout dommage qui vous serait caus\u00e9 par le fait d\u2019un tiers, qu\u2019il soit membre ou non de notre plate-forme. Nous nous r\u00e9servons de supprimer imm\u00e9diatement et sans pr\u00e9avis tout contenu qui pourrait enfreindre le droit de tiers, y compris le blocage de compte, et d\u2019en informer l\u2019ayant droit, le cas \u00e9ch\u00e9ant les autorit\u00e9s comp\u00e9tentes, lorsqu\u2019une telle obligation nous incombe.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2z28exj-9d191bcc1077d424e79a45c64115b86a'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-8' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-8'>8. PROTECTION DE VOS DONNEES<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-8' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p><strong>Nous respectons votre vie priv\u00e9e<\/strong> datalex s&#8217;engage \u00e0 n\u2019utiliser les informations que l&#8217;utilisateur lui communique que dans le cadre des prestations propos\u00e9es par le site et ne permettra l\u2019acc\u00e8s aux donn\u00e9es de l&#8217;utilisateur qu\u2019aux utilisateurs des services de datalex ou par des services tiers dans la mesure o\u00f9 un tel acc\u00e8s est n\u00e9cessaire pour le fonctionnement du service. En aucun cas nous ne vendons ni transmettons vos donn\u00e9es \u00e0 des tiers contre des avantages financiers. Pour plus d\u2019information, veuillez vous r\u00e9f\u00e9rer \u00e0 notre <a href=\"https:\/\/www.datalex.ch\/en\/privacy-notice\/\" target=\"_blank\" rel=\"noopener noreferrer\">politique de confidentialit\u00e9<\/a> ou nous contacter \u00e0 cette adresse\u00a0en cas de question : <a href=\"mailto:privacy@datalex.ch\" target=\"_blank\" rel=\"noopener noreferrer\">privacy@datalex.ch<\/a>.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2gvuvxz-363c2611f3dad89d39ab61f3cb71e058'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-9' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-9'>9. PROPRIETE INTELLECTUELLE<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-9' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Le site datalex.ch est prot\u00e9g\u00e9 par les droits de propri\u00e9t\u00e9 intellectuelle et en tant que raison de commerce. datalex est le titulaire exclusif de l&#8217;int\u00e9gralit\u00e9 des droits de propri\u00e9t\u00e9 intellectuelle sur le site et son contenu (textes, images, logos, scripts, base de donn\u00e9es, architecture, etc.) ainsi que de la marque suisse d\u00e9pos\u00e9e aupr\u00e8s de l\u2019office f\u00e9d\u00e9rale de la propri\u00e9t\u00e9 intellectuelle. Le contenu reproduit sur le site fait l\u2019objet d\u2019un droit d&#8217;auteur et sa reproduction ou sa diffusion, sans autorisation expresse \u00e9crite de datalex, constitue une contrefa\u00e7on passible de sanctions p\u00e9nales. Toute utilisation de nos contenus requiert notre accord pr\u00e9alable expr\u00e8s.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-20obxxz-b234b8af19ade2b241cd8e46f53fdce9'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-10' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-10'>10. MOT DE PASSE ET SECURITE INFORMATIQUE<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-10' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Le client s\u2019engage \u00e0 traiter les produits disponibles en ligne, les donn\u00e9es d\u2019acc\u00e8s au syst\u00e8me fournies ainsi que les mots de passe cr\u00e9\u00e9s de mani\u00e8re strictement confidentielle et avec le plus grand soin. datalex se r\u00e9serve le droit de mettre imm\u00e9diatement fin \u00e0 l\u2019autorisation d\u2019acc\u00e8s en cas de constatation d\u2019utilisation illicite ou contraire \u00e0 l\u2019\u00e9tendue de la licence qui vous est conf\u00e9r\u00e9e pour utiliser le Service.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-59643b-e60199d2d68d264eecd5351bde0b3c19'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-11' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-11'>11. DISPOSITIONS FINALES<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-11' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Au cas o\u00f9 certaines dispositions des pr\u00e9sentes conditions g\u00e9n\u00e9rales s\u2019av\u00e9reraient sans effet, la validit\u00e9 des autres dispositions n\u2019en sera pas affect\u00e9e. Les dispositions sans effet seront remplac\u00e9es par les dispositions l\u00e9gales analogues.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-1aogo53-5e1d27b6fd0cef6163926d73245573d6'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-12' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-12'>12. FOR ET DROIT APPLICABLE<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-12' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>Les relations contractuelles existant entre le client et datalex sont soumises au droit mat\u00e9riel suisse, \u00e0 l\u2019exclusion des dispositions de la Convention des Nations Unies du 11 avril 1980 sur la vente internationale des marchandises. Le tribunal ordinaire de l&#8217;arrondissement de l\u2019Est vaudois (Vevey) est comp\u00e9tent pour les litiges d\u00e9coulant du pr\u00e9sent contrat. En cas de contrat conclu avec un consommateur, le for juridique est au si\u00e8ge de la soci\u00e9t\u00e9, alternativement au for de son domicile.<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-ma2aemah-1797c16612f4af33bab5f40380ed71aa'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p data-fake-id='#toggle-id-13' class='toggler   av-inherit-border-color'  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-13'>13. CONTACT<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-13' class='toggle_wrap  '  ><div class='toggle_content invers-color av-inherit-border-color'  itemprop=\"text\" ><p>For questions or to contact us:<\/p>\n<p><strong>datalex s\u00e0rl <\/strong><br \/>\nc\/o Ludovic Tirelli<br \/>\nRue des Deux-Gares 6a<br \/>\nCH-1800 Vevey<br \/>\nCP 1140<br \/>\nSUISSE <\/p>\n<p>contact@datalex.ch<br \/>\nT.+41 21 925 30 90<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-32666","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms of use - datalex<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.datalex.ch\/en\/terms-of-use\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms of use - datalex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.datalex.ch\/en\/terms-of-use\/\" \/>\n<meta property=\"og:site_name\" content=\"datalex\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T09:10:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/terms-of-use\\\/\",\"url\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/terms-of-use\\\/\",\"name\":\"Terms of use - datalex\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/#website\"},\"datePublished\":\"2018-10-23T21:53:54+00:00\",\"dateModified\":\"2025-04-29T09:10:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/terms-of-use\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.datalex.ch\\\/en\\\/terms-of-use\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/terms-of-use\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms of use\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/\",\"name\":\"datalex\",\"description\":\"Avocats sp\u00e9cialis\u00e9s dans les nouvelles technologies - lawyers specializing in new technologies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.datalex.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms of use - datalex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.datalex.ch\/en\/terms-of-use\/","og_locale":"en_US","og_type":"article","og_title":"Terms of use - datalex","og_url":"https:\/\/www.datalex.ch\/en\/terms-of-use\/","og_site_name":"datalex","article_modified_time":"2025-04-29T09:10:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.datalex.ch\/en\/terms-of-use\/","url":"https:\/\/www.datalex.ch\/en\/terms-of-use\/","name":"Terms of use - datalex","isPartOf":{"@id":"https:\/\/www.datalex.ch\/en\/#website"},"datePublished":"2018-10-23T21:53:54+00:00","dateModified":"2025-04-29T09:10:59+00:00","breadcrumb":{"@id":"https:\/\/www.datalex.ch\/en\/terms-of-use\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.datalex.ch\/en\/terms-of-use\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.datalex.ch\/en\/terms-of-use\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.datalex.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Terms of use"}]},{"@type":"WebSite","@id":"https:\/\/www.datalex.ch\/en\/#website","url":"https:\/\/www.datalex.ch\/en\/","name":"datalex","description":"Avocats sp\u00e9cialis\u00e9s dans les nouvelles technologies - lawyers specializing in new technologies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.datalex.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/pages\/32666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/comments?post=32666"}],"version-history":[{"count":5,"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/pages\/32666\/revisions"}],"predecessor-version":[{"id":39004,"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/pages\/32666\/revisions\/39004"}],"wp:attachment":[{"href":"https:\/\/www.datalex.ch\/en\/wp-json\/wp\/v2\/media?parent=32666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}